{"id":4799,"date":"2024-06-25T10:24:03","date_gmt":"2024-06-25T08:24:03","guid":{"rendered":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/?post_type=mec-events&#038;p=4799"},"modified":"2024-06-25T10:24:03","modified_gmt":"2024-06-25T08:24:03","slug":"letture-per-bambini-4","status":"publish","type":"mec-events","link":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/","title":{"rendered":"Letture per bambini"},"content":{"rendered":"<p style=\"font-weight: 400;\">Ente richiedente: Biblioteca San Giovanni<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Ente richiedente: Biblioteca San Giovanni<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[35],"class_list":["post-4799","mec-events","type-mec-events","status-publish","hentry","mec_category-eventi-a-palazzo","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Letture per bambini &#187; Fondazione Cassa di Risparmio di Pesaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Letture per bambini &#187; Fondazione Cassa di Risparmio di Pesaro\" \/>\n<meta property=\"og:description\" content=\"Ente richiedente: Biblioteca San Giovanni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Cassa di Risparmio di Pesaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/events\\\/letture-per-bambini-4\\\/\",\"url\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/events\\\/letture-per-bambini-4\\\/\",\"name\":\"Letture per bambini &#187; Fondazione Cassa di Risparmio di Pesaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/#website\"},\"datePublished\":\"2024-06-25T08:24:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/events\\\/letture-per-bambini-4\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/events\\\/letture-per-bambini-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/events\\\/letture-per-bambini-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Letture per bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/\",\"name\":\"Fondazione Cassa di Risparmio di Pesaro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/#organization\",\"name\":\"Fondazione Cassa di Risparmio di Pesaro\",\"url\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-FCRP.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-FCRP.png\",\"width\":852,\"height\":173,\"caption\":\"Fondazione Cassa di Risparmio di Pesaro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionecrpesaro.it\\\/fondazione\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Letture per bambini &#187; Fondazione Cassa di Risparmio di Pesaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/","og_locale":"it_IT","og_type":"article","og_title":"Letture per bambini &#187; Fondazione Cassa di Risparmio di Pesaro","og_description":"Ente richiedente: Biblioteca San Giovanni","og_url":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/","og_site_name":"Fondazione Cassa di Risparmio di Pesaro","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/","url":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/","name":"Letture per bambini &#187; Fondazione Cassa di Risparmio di Pesaro","isPartOf":{"@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/#website"},"datePublished":"2024-06-25T08:24:03+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/letture-per-bambini-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/events\/"},{"@type":"ListItem","position":3,"name":"Letture per bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/#website","url":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/","name":"Fondazione Cassa di Risparmio di Pesaro","description":"","publisher":{"@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/#organization","name":"Fondazione Cassa di Risparmio di Pesaro","url":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-content\/uploads\/2021\/09\/logo-FCRP.png","contentUrl":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-content\/uploads\/2021\/09\/logo-FCRP.png","width":852,"height":173,"caption":"Fondazione Cassa di Risparmio di Pesaro"},"image":{"@id":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/mec-events\/4799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/comments?post=4799"}],"wp:attachment":[{"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/media?parent=4799"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/tags?post=4799"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.fondazionecrpesaro.it\/fondazione\/wp-json\/wp\/v2\/mec_category?post=4799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}